{"id":1110,"date":"2026-05-11T14:45:48","date_gmt":"2026-05-11T17:45:48","guid":{"rendered":"https:\/\/worldcreativity.org\/?p=1110"},"modified":"2026-05-11T14:58:22","modified_gmt":"2026-05-11T17:58:22","slug":"wco-members-apresentara-45-historias-de-impacto","status":"publish","type":"post","link":"https:\/\/worldcreativity.org\/pt\/wco-members-apresentara-45-historias-de-impacto\/","title":{"rendered":"WCO Members apresentar\u00e1 45 hist\u00f3rias de impacto em nova temporada"},"content":{"rendered":"<p>No ar a partir de 19 de maio, a s\u00e9rie <strong><em>WCD Impacto<\/em><\/strong> reunir\u00e1 lideran\u00e7as criativas brasileiras em talks de 20 minutos sobre transforma\u00e7\u00e3o, mobiliza\u00e7\u00e3o e impacto local gerados pelo World Creativity Day 2026.<\/p>\n\n\n\n<p>A World Creativity Organization lan\u00e7a, a partir do dia 19 de maio, a primeira edi\u00e7\u00e3o do <strong>WCD Impacto<\/strong>, nova s\u00e9rie de eventos online realizada dentro da plataforma <strong>WCO Members<\/strong>. A programa\u00e7\u00e3o acontece at\u00e9 12 de junho, sempre \u00e0s 10 horas. Reunindo <strong>45 lideran\u00e7as criativas brasileiras<\/strong> em apresenta\u00e7\u00f5es sobre os bastidores, aprendizados e resultados gerados pelo <strong>World Creativity Day<\/strong> em diferentes territ\u00f3rios do pa\u00eds, a s\u00e9rie transforma o momento de concluc\u00e3o do ciclo vivido pelas lideran\u00e7as em uma demonstra\u00e7\u00e3o emp\u00edrica de impacto e desenvolvimento.<\/p>\n\n\n\n<p>Em formato de talks online de 20 minutos, cada lideran\u00e7a compartilhar\u00e1 experi\u00eancias sobre mobiliza\u00e7\u00e3o comunit\u00e1ria, ativa\u00e7\u00e3o de espa\u00e7os, articula\u00e7\u00e3o de redes, conex\u00e3o entre pessoas e gera\u00e7\u00e3o de valor para profissionais, empreendedores, educadores, artistas, empresas locais, institui\u00e7\u00f5es p\u00fablicas e moradores de suas cidades.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03-1024x683.png\" alt=\"\" class=\"wp-image-1115\" srcset=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03-1024x683.png 1024w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03-300x200.png 300w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03-768x512.png 768w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03-18x12.png 18w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto03.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Mais do que uma apresenta\u00e7\u00e3o de resultados, o <strong>WCD Impacto<\/strong> nasce como uma s\u00e9rie editorial e institucional para mostrar como a criatividade, quando organizada em rede, pode se transformar em a\u00e7\u00e3o concreta nos territ\u00f3rios brasileiros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01-1024x683.png\" alt=\"\" class=\"wp-image-1111\" srcset=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01-1024x683.png 1024w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01-300x200.png 300w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01-768x512.png 768w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01-18x12.png 18w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto01.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Da certifica\u00e7\u00e3o ao impacto p\u00fablico<\/strong><\/h2>\n\n\n\n<p>O <strong>WCD Impacto<\/strong> amplia o alcance do processo formativo do CLP ao transformar a avalia\u00e7\u00e3o final das lideran\u00e7as em uma programa\u00e7\u00e3o aberta \u00e0 comunidade do WCO Members. A iniciativa conecta forma\u00e7\u00e3o, reconhecimento, conte\u00fado e presta\u00e7\u00e3o de contas em uma mesma experi\u00eancia.<\/p>\n\n\n\n<p>Ao apresentar as hist\u00f3rias por tr\u00e1s do maior festival colaborativo de criatividade do mundo, a s\u00e9rie tamb\u00e9m fortalece o papel do World Creativity Day como plataforma de desenvolvimento territorial. Cada talk revela como lideran\u00e7as locais mobilizaram comunidades, enfrentaram desafios, constru\u00edram parcerias e geraram impactos reais a partir da criatividade.<\/p>\n\n\n\n<p>A nova s\u00e9rie tamb\u00e9m inaugura uma frente estrat\u00e9gica de conte\u00fado para o ecossistema da World Creativity Organization, gerando registros, narrativas e evid\u00eancias sobre os efeitos do World Creativity Day em cidades brasileiras.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02-1024x768.png\" alt=\"\" class=\"wp-image-1112\" srcset=\"https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02-1024x768.png 1024w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02-300x225.png 300w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02-768x576.png 768w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02-16x12.png 16w, https:\/\/worldcreativity.org\/wp-content\/uploads\/2026\/05\/impacto02.png 1448w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Uma demonstra\u00e7\u00e3o real das lideran\u00e7as criativas brasileiras<\/strong><\/h2>\n\n\n\n<p>Com a realiza\u00e7\u00e3o do <strong>WCD Impacto<\/strong> dentro do WCO Members, a World Creativity Organization refor\u00e7a seu compromisso com a forma\u00e7\u00e3o, o reconhecimento e a proje\u00e7\u00e3o internacional de lideran\u00e7as criativas capazes de transformar seus territ\u00f3rios.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o apresenta uma rede nacional em movimento: pessoas que lideraram a\u00e7\u00f5es locais, conectaram comunidades e mostraram, na pr\u00e1tica, como a criatividade pode ser uma for\u00e7a de pertencimento, aprendizagem, colabora\u00e7\u00e3o e desenvolvimento.<\/p>\n\n\n\n<p><strong>WCD Impacto \u00e9 o palco das lideran\u00e7as criativas que transformam o World Creativity Day em impacto real nos territ\u00f3rios brasileiros.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>No ar a partir de 19 de maio, a s\u00e9rie WCD Impacto reunir\u00e1 lideran\u00e7as criativas brasileiras em talks de 20 minutos sobre transforma\u00e7\u00e3o, mobiliza\u00e7\u00e3o e impacto local gerados pelo World Creativity Day 2026. A World Creativity Organization lan\u00e7a, a partir do dia 19 de maio, a primeira edi\u00e7\u00e3o do WCD Impacto, nova s\u00e9rie de eventos [&hellip;]<\/p>","protected":false},"author":36,"featured_media":1113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"_links":{"self":[{"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/posts\/1110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/comments?post=1110"}],"version-history":[{"count":7,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/posts\/1110\/revisions"}],"predecessor-version":[{"id":1124,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/posts\/1110\/revisions\/1124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/media\/1113"}],"wp:attachment":[{"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/media?parent=1110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/categories?post=1110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldcreativity.org\/pt\/wp-json\/wp\/v2\/tags?post=1110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}